{"id":7657,"date":"2022-08-04T14:10:36","date_gmt":"2022-08-04T17:10:36","guid":{"rendered":"https:\/\/certificadocursosonline.com\/blog\/?p=7657"},"modified":"2023-02-27T14:23:09","modified_gmt":"2023-02-27T17:23:09","slug":"fatores-de-rankeamento-do-google","status":"publish","type":"post","link":"https:\/\/certificadocursosonline.com\/blog\/fatores-de-rankeamento-do-google\/","title":{"rendered":"Conhe\u00e7a os fatores de rankeamento do Google"},"content":{"rendered":"<p><span style=\"font-weight: 400;\">A Internet possui papel crucial nas estrat\u00e9gias de marketing. Ali\u00e1s, antes da alta nas tend\u00eancias de marketing digital, outros m\u00e9todos receberam notoriedade, como o sistema de <\/span><b>rankeamento <\/b><span style=\"font-weight: 400;\">de p\u00e1ginas, que \u00e9 feito pelo <a href=\"https:\/\/certificadocursosonline.com\/cursos\/curso-de-como-ganhar-dinheiro-com-o-google-adsense\/\" target=\"_blank\" rel=\"noopener noreferrer\">Google<\/a>.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">As p\u00e1ginas na web possuem familiaridade com os an\u00fancios de jornais, os quais eram o principal ve\u00edculo de comunica\u00e7\u00e3o das estrat\u00e9gias de marketing. <\/span><\/p>\n<p><span style=\"font-weight: 400;\">Entretanto, com a velocidade na troca de informa\u00e7\u00e3o, demais meios foram destacados.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Para uma empresa fornecedora do servi\u00e7o de <\/span><a href=\"http:\/\/www.novaeradrenagem.com.br\/caixas-pre-moldadas\/drenagem-de-aguas-pluviais-em-terrenos\" target=\"_blank\" rel=\"noopener noreferrer\"><b>drenagem de \u00e1guas pluviais em terrenos<\/b><\/a><span style=\"font-weight: 400;\">, direcionar os recursos para a Internet foi essencial no sentido de potencializar os resultados e com baixo investimento.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Devido \u00e0 pluralidade vista no meio virtual, isto \u00e9, a capacidade de atingir um amplo n\u00famero de pessoas com poucas movimenta\u00e7\u00f5es, se faz indispens\u00e1vel um levantamento de p\u00fablico, o qual deve estar alinhado com os objetivos gerais e espec\u00edficos da empresa.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">O respaldo de um planejamento auxilia na etapa de segmenta\u00e7\u00e3o, bem como o apoio no encontro do nicho de mercado adequado, aumentando as oportunidades de atingir os efetivos clientes com interesse em <\/span><a href=\"http:\/\/www.northpetshop.com.br\/pet-shop\/veterinarios-para-animais-exoticos\/centro-veterinario-de-animais-exoticos\/veterinario-especializado-em-aves-tucuruvi\" target=\"_blank\" rel=\"noopener noreferrer\"><b>veterin\u00e1rio especializado em aves<\/b><\/a><span style=\"font-weight: 400;\">.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Embora tenha conquistado popularidade nos \u00faltimos anos, o marketing, incluindo na sua modalidade tradicional, \u00e9 um recurso relevante nas organiza\u00e7\u00f5es.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Sendo assim, pode-se levar em pauta as t\u00e9cnicas de SEO, um recurso preciso nas estrat\u00e9gias de marketing digital.<\/span><\/p>\n<h2><strong>O que \u00e9 o SEO?<\/strong><\/h2>\n<p><span style=\"font-weight: 400;\">Entende-se por <\/span><i><span style=\"font-weight: 400;\">Search Engine Optimization<\/span><\/i><span style=\"font-weight: 400;\">, ou SEO, um conjunto de t\u00e9cnicas aplicadas em conte\u00fados publicados na web, com a finalidade de aproximar leitores e clientes em potencial das empresas que concentram a\u00e7\u00f5es na internet.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Paralelamente ao apelo da acelera\u00e7\u00e3o digital feito no mercado, as companhias dos mais variados segmentos e portes foram convidadas a fazer adapta\u00e7\u00f5es, vislumbrando atender a demanda corriqueiramente fomentada.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Isto \u00e9, para que um pequeno neg\u00f3cio local pudesse refor\u00e7ar a autoridade em seu nicho de atua\u00e7\u00e3o, foi crucial contar com o apoio da Internet para anunciar o oferecimento de diferentes solu\u00e7\u00f5es ao p\u00fablico, como <\/span><a href=\"http:\/\/www.mundodechocolate.com.br\/alcool-gel-lembrancinha-maternidade\" target=\"_blank\" rel=\"noopener noreferrer\"><b>lembrancinha de \u00e1lcool em gel<\/b><\/a><span style=\"font-weight: 400;\">.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Tendo em vista que a comunica\u00e7\u00e3o \u00e9 o principal caminho para os neg\u00f3cios, quando se est\u00e1 presente na Internet, \u00e9 essencial dispor das diferentes linguagens da comunica\u00e7\u00e3o. Entre elas, podem ser enfatizadas:<\/span><\/p>\n<ul>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><strong>Comunica\u00e7\u00e3o escrita;<\/strong><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><strong>Comunica\u00e7\u00e3o verbal;<\/strong><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><strong>Comunica\u00e7\u00e3o n\u00e3o verbal;<\/strong><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><strong>Comunica\u00e7\u00e3o visual.<\/strong><\/li>\n<\/ul>\n<p><span style=\"font-weight: 400;\">Essas s\u00e3o as principais formas de linguagem utilizadas pelas pessoas, no geral, e que tamb\u00e9m podem ser vistas nas estrat\u00e9gias empresariais e aplicadas nas negocia\u00e7\u00f5es.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Contextualizando com o funcionamento da Internet, deve-se considerar que o ambiente virtual \u00e9 separado por sites e p\u00e1ginas, os quais cont\u00eam endere\u00e7os individuais que correspondem a determinadas empresas.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Al\u00e9m disso, analisando os impactos de quest\u00f5es como o alto volume de informa\u00e7\u00f5es transitadas e as movimenta\u00e7\u00f5es da demanda, as empresas precisam diferenciar o modo de abordagem de clientes, neste caso, leitores.<\/span><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-7660 size-full\" src=\"https:\/\/certificadocursosonline.com\/blog\/wp-content\/uploads\/2022\/08\/O-que-\u00e9-o-SEO.jpg\" alt=\"O que \u00e9 o SEO?\" width=\"640\" height=\"427\" srcset=\"https:\/\/certificadocursosonline.com\/blog\/wp-content\/uploads\/2022\/08\/O-que-\u00e9-o-SEO.jpg 640w, https:\/\/certificadocursosonline.com\/blog\/wp-content\/uploads\/2022\/08\/O-que-\u00e9-o-SEO-300x200.jpg 300w, https:\/\/certificadocursosonline.com\/blog\/wp-content\/uploads\/2022\/08\/O-que-\u00e9-o-SEO-364x243.jpg 364w, https:\/\/certificadocursosonline.com\/blog\/wp-content\/uploads\/2022\/08\/O-que-\u00e9-o-SEO-608x406.jpg 608w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/p>\n<p><span style=\"font-weight: 400;\">Se por um lado abordagens diretas e inteiramente comerciais t\u00eam se mostrado dificultosas no meio virtual, a divulga\u00e7\u00e3o de conte\u00fados se apresenta como o recurso atual para potencializar servi\u00e7os de<\/span> <a href=\"http:\/\/www.multiformasmodulados.com.br\/balcoes\/instalacao-para-loja-de-roupas\" target=\"_blank\" rel=\"noopener noreferrer\"><b>instala\u00e7\u00e3o de loja<\/b><\/a><span style=\"font-weight: 400;\"> com o marketing digital.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">O chamado marketing de conte\u00fado \u00e9 uma modalidade das a\u00e7\u00f5es promocionais e de publicidade presentes na Internet, exigindo a cria\u00e7\u00e3o de textos para sites e p\u00e1ginas na web.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">As t\u00e9cnicas de SEO s\u00e3o aplicadas nos textos publicados, consistindo no uso de palavras-chave e termos procurados com frequ\u00eancia pelos clientes em potencial na Internet.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">A estrat\u00e9gia faz o uso do rankeamento para mostrar os resultados e, por isso, \u00e9 conhecida tamb\u00e9m como a otimiza\u00e7\u00e3o dos mecanismos de busca.<\/span><\/p>\n<h2><strong>Conhe\u00e7a o rankeamento na pr\u00e1tica<\/strong><\/h2>\n<p><span style=\"font-weight: 400;\">Na pr\u00e1tica, o funcionamento do sistema de otimiza\u00e7\u00e3o dos mecanismos de busca atua diretamente com a an\u00e1lise feita pelos algoritmos.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Os algoritmos s\u00e3o sistemas presentes em diferentes mecanismos de busca, como a ferramenta Google, que fazem de forma autom\u00e1tica a classifica\u00e7\u00e3o de p\u00e1ginas e sites condizentes com a pesquisa feita pelos usu\u00e1rios.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">A partir disso, os algoritmos, que tamb\u00e9m s\u00e3o um sistema de intelig\u00eancia artificial e programada, fazem a leitura das palavras-chave, passando a sugerir p\u00e1ginas que podem interessar ao leitor.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Visando exemplificar o funcionamento, pode-se considerar que um usu\u00e1rio inseriu as palavras-chave para pesquisar sobre <\/span><a href=\"http:\/\/www.mpr.com.br\/carrinhos-promocionais\/banner-para-loja-de-roupas\" target=\"_blank\" rel=\"noopener noreferrer\"><b>banner para loja feminina<\/b><\/a><span style=\"font-weight: 400;\"> na barra de pesquisa da plataforma de busca.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Em conformidade com a programa\u00e7\u00e3o feita pela equipe desenvolvedora da ferramenta, os algoritmos fazem a an\u00e1lise dos termos questionados e, assim, passam a apresentar uma s\u00e9rie de resultados de acordo com aquilo que foi pesquisado.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Todavia, ao notar a relev\u00e2ncia que esse recurso possui, as empresas fornecedoras das ferramentas de busca, e ainda as ag\u00eancias de marketing, elaboraram estudos para rentabilizar a funcionalidade.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Ou seja, se antes uma loja virtual precisava apenas elaborar o site de maneira simples e compartilhar os an\u00fancios e conte\u00fados ao p\u00fablico, atualmente, \u00e9 crucial dispor de t\u00e9cnicas para alavancar as vendas de <\/span><a href=\"https:\/\/moveis.comave.com.br\/cadeira-para-escritorio-sem-rodinha\" target=\"_blank\" rel=\"noopener noreferrer\"><b>cadeira para escrit\u00f3rio sem rodinha<\/b><\/a><span style=\"font-weight: 400;\">.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Isso se d\u00e1 devido ao alto volume de informa\u00e7\u00f5es compartilhadas diariamente na web, pois, com isso, os leitores passaram a ser ainda mais seletivos para com os conte\u00fados consumidos. Neste cen\u00e1rio, se d\u00e1 a aplica\u00e7\u00e3o das t\u00e9cnicas de SEO no rankeamento.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Visto que, ao incluir as palavras-chave e termos regularmente pesquisados com o p\u00fablico-alvo, neste sentido, clientes em potencial, os conte\u00fados publicados recebem maior acesso e, por consequ\u00eancia, uma posi\u00e7\u00e3o de destaque no hall de resultados.<\/span><\/p>\n<h2><strong>Saiba sobre os fatores de rankeamento<\/strong><\/h2>\n<p><span style=\"font-weight: 400;\">Ap\u00f3s o entendimento generalizado do sistema de rankeamento, pode-se levar em conta que foram desenvolvidos estudos para aprimorar o modo pelo qual os resultados s\u00e3o exibidos em tela aos usu\u00e1rios.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Em outras palavras, isso significa que, al\u00e9m dos cliques feitos pelos usu\u00e1rios, outros pontos s\u00e3o levados em considera\u00e7\u00e3o durante a an\u00e1lise de algoritmos para determinar a posi\u00e7\u00e3o que uma p\u00e1gina ter\u00e1.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">\u00c9 importante validar que segmentos espec\u00edficos requerem a aplica\u00e7\u00e3o direta de palavras-chave, ou seja, aplica\u00e7\u00e3o de termos que efetivamente condizem com o nicho de pessoas e p\u00fablico a ser atingido.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Se presencialmente o nicho de clientes de <\/span><a href=\"https:\/\/www.motoboycentral.com.br\/transporte-de-carga-em-motocicleta\" target=\"_blank\" rel=\"noopener noreferrer\"><b>transporte de carga em motocicleta<\/b><\/a><span style=\"font-weight: 400;\"> \u00e9 diferente de uma empresa distribuidora de flores, por exemplo, na Internet estes fatores precisam ser observados.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Ali\u00e1s, a segmenta\u00e7\u00e3o \u00e9 indispens\u00e1vel nas estrat\u00e9gias e modalidades de marketing digital, uma vez que o ambiente virtual possibilita o aumento de clientes em potencial a serem contatados.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Por isso, deve-se ter em mente que o processo de rankeamento feito pelos mecanismos de busca possui o respaldo de diferentes fatores.<\/span><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-7659 size-full\" src=\"https:\/\/certificadocursosonline.com\/blog\/wp-content\/uploads\/2022\/08\/Saiba-sobre-os-fatores-de-rankeamento.jpg\" alt=\"Saiba sobre os fatores de rankeamento\" width=\"640\" height=\"427\" srcset=\"https:\/\/certificadocursosonline.com\/blog\/wp-content\/uploads\/2022\/08\/Saiba-sobre-os-fatores-de-rankeamento.jpg 640w, https:\/\/certificadocursosonline.com\/blog\/wp-content\/uploads\/2022\/08\/Saiba-sobre-os-fatores-de-rankeamento-300x200.jpg 300w, https:\/\/certificadocursosonline.com\/blog\/wp-content\/uploads\/2022\/08\/Saiba-sobre-os-fatores-de-rankeamento-364x243.jpg 364w, https:\/\/certificadocursosonline.com\/blog\/wp-content\/uploads\/2022\/08\/Saiba-sobre-os-fatores-de-rankeamento-608x406.jpg 608w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/p>\n<p><strong>S\u00e3o eles:<\/strong><\/p>\n<h3><strong>1. Pagerank<\/strong><\/h3>\n<p><span style=\"font-weight: 400;\">O primeiro fator em pauta trata-se de uma m\u00e9trica que qualifica as palavras-chave usadas em uma p\u00e1gina ou site. <\/span><\/p>\n<p><span style=\"font-weight: 400;\">A qualifica\u00e7\u00e3o se d\u00e1 a partir de notas que indicam a autoridade, qualidade e quantidade de links de uma p\u00e1gina.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Entretanto, assim como boa parte dos recursos fundamentais para o bom andamento de estrat\u00e9gias organizacionais, o Pagerank deixou de ser um dado transparente e p\u00fablico, tornando-se um recurso pago.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Sabendo da funcionalidade que o recurso possui para as estrat\u00e9gias de SEO e do marketing de conte\u00fado, foi encontrada outra plataforma com funcionamento semelhante. A alternativa \u00e9 o Page Authority.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">A principal diferen\u00e7a entre os recursos similares, \u00e9 que a an\u00e1lise feita pelo Page Authority acerca do conte\u00fado publicado na web com t\u00e9cnicas de SEO para <\/span><a href=\"https:\/\/www.montagengenharia.com.br\/automacao-industrial\/instalacao-eletrica\/instalacao-eletrica-estilo-industrial\/instalacao-eletrica-aparente-externa-barueri\" target=\"_blank\" rel=\"noopener noreferrer\"><b>instala\u00e7\u00e3o el\u00e9trica aparente externa<\/b><\/a><span style=\"font-weight: 400;\">, conta com a observa\u00e7\u00e3o logar\u00edtmica e n\u00e3o algor\u00edtmica.<\/span><\/p>\n<h3><strong>2. Autoridade de dom\u00ednio<\/strong><\/h3>\n<p><span style=\"font-weight: 400;\">O<\/span><i><span style=\"font-weight: 400;\"> Domain Authority<\/span><\/i><span style=\"font-weight: 400;\">, ou autoridade de dom\u00ednio, \u00e9 uma an\u00e1lise metrificada por uma fornecedora de ferramentas para marketing digital, que faz o uso de diferentes crit\u00e9rios para mensurar a autoridade e qualidade de uma p\u00e1gina na Internet.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Toda p\u00e1gina possui um dom\u00ednio, porquanto, a an\u00e1lise feita se expande para demais sites e dom\u00ednios relacionados com o dom\u00ednio principal, avaliando, assim, a autoridade e confiabilidade no momento de rankear.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Vislumbrando uma an\u00e1lise mais assertiva, o Domain Authority conta com a observa\u00e7\u00e3o por notas que variam de um a cem, sendo o n\u00famero maior o qual aponta mais autoridade ao dom\u00ednio.<\/span><\/p>\n<h3><strong>3. Relev\u00e2ncia dos links<\/strong><\/h3>\n<p><span style=\"font-weight: 400;\">Outro fator de import\u00e2ncia \u00e9 a quantidade de vezes em que um link foi usado em p\u00e1ginas. Esse ponto se trata n\u00e3o das fontes de links utilizadas, mas sim do processo reverso.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Quanto mais vezes um link ou p\u00e1gina for referenciado por outros sites na Internet, maior ser\u00e1 a posi\u00e7\u00e3o obtida pelo neg\u00f3cio nos resultados exibidos na tela do cliente e usu\u00e1rio. <\/span><\/p>\n<p><span style=\"font-weight: 400;\">O processo pode acontecer inteiramente de maneira org\u00e2nica.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Mas, uma vez que um dos principais objetivos da Internet \u00e9 potencializar o alcance das t\u00e9cnicas de maneira assertiva, subentende-se que \u00e9 preciso dispor de m\u00e9todos adicionais em prol do crescimento r\u00e1pido.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Com isso, uma estrat\u00e9gia de link building \u00e9 recomendada neste cen\u00e1rio, dispondo tamb\u00e9m do desenvolvimento de parcerias estrat\u00e9gicas para blogs complementares ao do neg\u00f3cio.<\/span><\/p>\n<h3><strong>4. Conte\u00fado, estrutura e qualidade<\/strong><\/h3>\n<p><span style=\"font-weight: 400;\">Conte\u00fado, estrutura e qualidade s\u00e3o aspectos essenciais a serem analisados no momento de cria\u00e7\u00e3o de conte\u00fados para a Internet. <\/span><\/p>\n<p><span style=\"font-weight: 400;\">Por isso, \u00e9 indispens\u00e1vel estar atento para as normas e recomenda\u00e7\u00f5es feitas pela ABNT (Associa\u00e7\u00e3o Brasileira de Normas T\u00e9cnicas).<\/span><\/p>\n<h2><strong>Considera\u00e7\u00f5es finais<\/strong><\/h2>\n<p><span style=\"font-weight: 400;\">O Google apresenta-se como um das principais plataformas com ferramentas empresariais, apoiando desde o funcionamento do operacional, e estendendo-se at\u00e9 a constru\u00e7\u00e3o de campanhas.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Contudo, o sistema de rankeamento feito pelo Google, e pelos demais mecanismos de busca, exige o uso de t\u00e9cnicas em prol do ganho de notoriedade das p\u00e1ginas.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Internet possui papel crucial nas estrat\u00e9gias de marketing. Ali\u00e1s, antes da alta nas tend\u00eancias de marketing digital, outros m\u00e9todos receberam notoriedade, como o sistema de rankeamento de p\u00e1ginas, que \u00e9 feito pelo Google. As p\u00e1ginas na web possuem familiaridade com os an\u00fancios de jornais, os quais eram o principal ve\u00edculo de comunica\u00e7\u00e3o das estrat\u00e9gias [&hellip;] <a class=\"g1-link g1-link-more\" href=\"https:\/\/certificadocursosonline.com\/blog\/fatores-de-rankeamento-do-google\/\">Mais<\/a><\/p>\n","protected":false},"author":3,"featured_media":7658,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[31,455],"tags":[1011],"class_list":{"0":"post-7657","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-outras-areas","8":"category-tecnologia","9":"tag-conheca-os-fatores-de-rankeamento-do-google"},"wps_subtitle":"","_links":{"self":[{"href":"https:\/\/certificadocursosonline.com\/blog\/wp-json\/wp\/v2\/posts\/7657","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/certificadocursosonline.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/certificadocursosonline.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/certificadocursosonline.com\/blog\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/certificadocursosonline.com\/blog\/wp-json\/wp\/v2\/comments?post=7657"}],"version-history":[{"count":2,"href":"https:\/\/certificadocursosonline.com\/blog\/wp-json\/wp\/v2\/posts\/7657\/revisions"}],"predecessor-version":[{"id":8844,"href":"https:\/\/certificadocursosonline.com\/blog\/wp-json\/wp\/v2\/posts\/7657\/revisions\/8844"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/certificadocursosonline.com\/blog\/wp-json\/wp\/v2\/media\/7658"}],"wp:attachment":[{"href":"https:\/\/certificadocursosonline.com\/blog\/wp-json\/wp\/v2\/media?parent=7657"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/certificadocursosonline.com\/blog\/wp-json\/wp\/v2\/categories?post=7657"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/certificadocursosonline.com\/blog\/wp-json\/wp\/v2\/tags?post=7657"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}